{"id":774,"date":"2023-07-25T15:14:46","date_gmt":"2023-07-25T07:14:46","guid":{"rendered":"https:\/\/kampungcameron.com\/2023\/07\/25\/%e6%b8%85%e6%96%b0%e8%b6%8a%e5%8d%97%e9%a3%8e%e6%83%85%e5%8d%b7\/"},"modified":"2023-08-02T23:36:39","modified_gmt":"2023-08-02T15:36:39","slug":"%e6%b8%85%e6%96%b0%e8%b6%8a%e5%8d%97%e9%a3%8e%e6%83%85%e5%8d%b7","status":"publish","type":"post","link":"https:\/\/kampungcameron.com\/zh-hans\/2023\/07\/25\/%e6%b8%85%e6%96%b0%e8%b6%8a%e5%8d%97%e9%a3%8e%e6%83%85%e5%8d%b7\/","title":{"rendered":"\u6e05\u65b0\u8d8a\u5357\u98ce\u60c5\u5377"},"content":{"rendered":"<div class=\"row row-large\"  id=\"row-319269659\">\n\n\n\t<div id=\"col-60804387\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover recipe-img x md-x lg-x y md-y lg-y\" id=\"image_1733826295\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/Veitnam.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/Veitnam.jpg 1500w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/Veitnam-300x200.jpg 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/Veitnam-1024x683.jpg 1024w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/Veitnam-768x512.jpg 768w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/Veitnam-600x400.jpg 600w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1733826295 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-1450000255\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1450000255 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h5>\u505a\u6cd5:<\/h5>\n<ol>\n<li>\u5c06\u852c\u83dc\u6d17\u51c0\uff1b\u7ea2\u841d\u535c\u3001\u7ea2\u9752\u6912\u5207\u4e1d\uff0c\u8d8a\u624b\u6307\u957f\u5ea6\u5907\u7528\u3002<\/li>\n<li>\u5c06\u7ea2\u841d\u535c\u712f\u6c34\u5907\u7528\uff0c\u4e0d\u9700\u8981\u716e\u5f97\u592a\u719f\uff0c\u4fdd\u6301\u6e05\u8106\u53e3\u611f\u5373\u53ef\u3002<\/li>\n<li>\u867e\u5b50\u5265\u58f3\u540e\u712f\u719f\u3002<\/li>\n<li>\u5c06\u6625\u5377\u76ae\u653e\u5165\u51c9\u6c34\u91cc\u6d78\u6ce1\u534a\u5206\u949f\uff0c\u611f\u89c9\u76ae\u5b50\u53d8\u8f6f\u5373\u523b\u62ff\u51fa\u3002<\/li>\n<li>\u5c0f\u8d34\u58eb-\u6d78\u6ce1\u65f6\u95f4\u4e0d\u80fd\u8fc7\u957f\uff0c\u4e5f\u4e0d\u8981\u8fc7\u70ed\uff0c\u907f\u514d\u6625\u5377\u76ae\u7834\u788e\u3002<\/li>\n<li>\u628a\u5df2\u7ecf\u6d78\u8f6f\u7684\u6625\u5377\u76ae\u5e73\u94fa\u5f00\uff0c\u5148\u653e\u867e\u4ec1\u3001\u751f\u83dc\u3001\u8584\u8377 \u518d\u628a\u5176\u4ed6\u852c\u83dc\u53e0\u653e\u5728\u4e0a\u65b9\u3002<\/li>\n<li>\u6750\u6599\u653e\u597d\u540e\uff0c\u5c0f\u5fc3\u5730\u5c06\u6625\u5377\u76ae\u5377\u8d77\u6765\u3002<\/li>\n<li>\u5377\u597d\u540e\uff0c\u53ef\u4ee5\u8638\u70b9\u9c7c\u9732\u6216\u751c\u8fa3\u9171\u98df\u7528\u3002<\/li>\n<\/ol>\n<h5>\u8c03\u6c41\u505a\u6cd5:<\/h5>\n<ol>\n<li>\u5c06\u849c\u5934\u3001\u5c0f\u8fa3\u6912\u3001\u9999\u83dc\u5207\u788e\uff0c\u52a0\u5165\u5176\u5b83\u98df\u6750 \u6405\u62cc\u5747\u5300\u5373\u53ef\u98df\u7528\u3002<\/li>\n<\/ol>\n<div class=\"social-icons share-icons share-row relative icon-style-fill\" ><a href=\"whatsapp:\/\/send?text=%E6%B8%85%E6%96%B0%E8%B6%8A%E5%8D%97%E9%A3%8E%E6%83%85%E5%8D%B7 - https:\/\/kampungcameron.com\/zh-hans\/2023\/07\/25\/%e6%b8%85%e6%96%b0%e8%b6%8a%e5%8d%97%e9%a3%8e%e6%83%85%e5%8d%b7\/\" data-action=\"share\/whatsapp\/share\" class=\"icon primary button circle tooltip whatsapp show-for-medium\" title=\"\u5206\u4eab\u5230WhatsApp\" aria-label=\"\u5206\u4eab\u5230WhatsApp\" ><i class=\"icon-whatsapp\" ><\/i><\/a><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/kampungcameron.com\/zh-hans\/2023\/07\/25\/%e6%b8%85%e6%96%b0%e8%b6%8a%e5%8d%97%e9%a3%8e%e6%83%85%e5%8d%b7\/\" data-label=\"Facebook\" onclick=\"window.open(this.href,this.title,'width=500,height=500,top=300px,left=300px'); return false;\" target=\"_blank\" class=\"icon primary button circle tooltip facebook\" title=\"\u5206\u4eab\u5230Facebook\" aria-label=\"\u5206\u4eab\u5230Facebook\" rel=\"noopener nofollow\" ><i class=\"icon-facebook\" ><\/i><\/a><a href=\"https:\/\/twitter.com\/share?url=https:\/\/kampungcameron.com\/zh-hans\/2023\/07\/25\/%e6%b8%85%e6%96%b0%e8%b6%8a%e5%8d%97%e9%a3%8e%e6%83%85%e5%8d%b7\/\" onclick=\"window.open(this.href,this.title,'width=500,height=500,top=300px,left=300px'); return false;\" target=\"_blank\" class=\"icon primary button circle tooltip twitter\" title=\"\u5206\u4eab\u5230Twitter\" aria-label=\"\u5206\u4eab\u5230Twitter\" rel=\"noopener nofollow\" ><i class=\"icon-twitter\" ><\/i><\/a><a href=\"mailto:?subject=%E6%B8%85%E6%96%B0%E8%B6%8A%E5%8D%97%E9%A3%8E%E6%83%85%E5%8D%B7&body=Check%20this%20out%3A%20https%3A%2F%2Fkampungcameron.com%2Fzh-hans%2F2023%2F07%2F25%2F%25e6%25b8%2585%25e6%2596%25b0%25e8%25b6%258a%25e5%258d%2597%25e9%25a3%258e%25e6%2583%2585%25e5%258d%25b7%2F\" class=\"icon primary button circle tooltip email\" title=\"\u53d1\u90ae\u4ef6\u7ed9\u670b\u53cb\" aria-label=\"\u53d1\u90ae\u4ef6\u7ed9\u670b\u53cb\" rel=\"nofollow\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"https:\/\/pinterest.com\/pin\/create\/button?url=https:\/\/kampungcameron.com\/zh-hans\/2023\/07\/25\/%e6%b8%85%e6%96%b0%e8%b6%8a%e5%8d%97%e9%a3%8e%e6%83%85%e5%8d%b7\/&media=https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/Veitnam-1024x683.jpg&description=%E6%B8%85%E6%96%B0%E8%B6%8A%E5%8D%97%E9%A3%8E%E6%83%85%E5%8D%B7\" onclick=\"window.open(this.href,this.title,'width=500,height=500,top=300px,left=300px'); return false;\" target=\"_blank\" class=\"icon primary button circle tooltip pinterest\" title=\"\u5206\u4eab\u5230Pinterest\" aria-label=\"\u5206\u4eab\u5230Pinterest\" rel=\"noopener nofollow\" ><i class=\"icon-pinterest\" ><\/i><\/a><a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/kampungcameron.com\/zh-hans\/2023\/07\/25\/%e6%b8%85%e6%96%b0%e8%b6%8a%e5%8d%97%e9%a3%8e%e6%83%85%e5%8d%b7\/&title=%E6%B8%85%E6%96%B0%E8%B6%8A%E5%8D%97%E9%A3%8E%E6%83%85%E5%8D%B7\" onclick=\"window.open(this.href,this.title,'width=500,height=500,top=300px,left=300px'); return false;\" target=\"_blank\" class=\"icon primary button circle tooltip linkedin\" title=\"\u5206\u4eab\u5230LinkedIn\" aria-label=\"\u5206\u4eab\u5230LinkedIn\" rel=\"noopener nofollow\" ><i class=\"icon-linkedin\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1198966298\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>\u65b0\u9c9c\u8d8a\u5357\u6625\u5377\uff0c\u7528\u6e05\u723d\u7684\u6625\u5377\u76ae\u5305\u88f9\u867e\u4ec1\u3001\u751f\u83dc\u3001\u8584\u8377\u7b49\u4e30\u5bcc\u852c\u83dc\uff0c\u914d\u4ee5\u7f8e\u5473\u7684\u8c03\u5473\u6599 \u53e3\u611f\u9c9c\u7f8e\uff0c\u662f\u4e00\u9053\u8ba9\u4eba\u56de\u5473\u65e0\u7a77\u7684\u4f73\u80b4\u3002\n<\/p>\n<h5>\u6750\u6599:<\/h5>\n\n\t\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-300x300.jpg 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-150x150.jpg 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-100x100.jpg 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u6625\u5377\u76ae 8\u5f20<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-300x300.jpg 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-150x150.jpg 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-100x100.jpg 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u867e\u7ea6 16\u53ea<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t<a class=\"plain\" href=\"https:\/\/kampungcameron.com\/product\/icerberg-lettuce\/\" >\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/B06-Iceberg-Lettuce-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/B06-Iceberg-Lettuce-300x300.png 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/B06-Iceberg-Lettuce-150x150.png 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/B06-Iceberg-Lettuce-768x768.png 768w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/B06-Iceberg-Lettuce-600x600.png 600w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/B06-Iceberg-Lettuce-100x100.png 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/B06-Iceberg-Lettuce.png 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u751f\u83dc 8\u53f6<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t<a class=\"plain\" href=\"https:\/\/kampungcameron.com\/product\/mint-leaves\/\" >\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-300x300.jpg 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-150x150.jpg 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-100x100.jpg 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u8584\u8377\u53f6<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t<a class=\"plain\" href=\"https:\/\/kampungcameron.com\/product\/carrot\/\" >\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D01-Carrot_2-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D01-Carrot_2-300x300.png 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D01-Carrot_2-150x150.png 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D01-Carrot_2-768x768.png 768w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D01-Carrot_2-600x600.png 600w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D01-Carrot_2-100x100.png 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D01-Carrot_2.png 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u7ea2\u841d\u535c \u4e00\u6761<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t<a class=\"plain\" href=\"https:\/\/kampungcameron.com\/zh-hans\/product\/red-capsicum\/\" >\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C12-Red-Capsicum-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C12-Red-Capsicum-300x300.png 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C12-Red-Capsicum-150x150.png 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C12-Red-Capsicum-768x768.png 768w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C12-Red-Capsicum-600x600.png 600w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C12-Red-Capsicum-100x100.png 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C12-Red-Capsicum.png 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u7ea2\u9752\u6912 \u4e00\u9897<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t<a class=\"plain\" href=\"https:\/\/kampungcameron.com\/product\/garlic-chives-kuchai\/\" >\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A23-Garlic-Chives-Kuchai-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A23-Garlic-Chives-Kuchai-300x300.jpg 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A23-Garlic-Chives-Kuchai-150x150.jpg 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A23-Garlic-Chives-Kuchai-768x768.jpg 768w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A23-Garlic-Chives-Kuchai-600x600.jpg 600w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A23-Garlic-Chives-Kuchai-100x100.jpg 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A23-Garlic-Chives-Kuchai.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u97ed\u83dc \u7ea64\u6761<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t<a class=\"plain\" href=\"https:\/\/kampungcameron.com\/product\/garlic-6-7cm\/\" >\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D05-Garlic_2-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D05-Garlic_2-300x300.png 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D05-Garlic_2-150x150.png 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D05-Garlic_2-768x768.png 768w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D05-Garlic_2-600x600.png 600w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D05-Garlic_2-100x100.png 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/D05-Garlic_2.png 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u849c\u59342\u74e3<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t<a class=\"plain\" href=\"https:\/\/kampungcameron.com\/zh-hans\/product\/red-chilli\/\" >\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C15-Red-Chilli_2-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C15-Red-Chilli_2-300x300.png 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C15-Red-Chilli_2-150x150.png 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C15-Red-Chilli_2-768x768.png 768w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C15-Red-Chilli_2-600x600.png 600w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C15-Red-Chilli_2-100x100.png 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/C15-Red-Chilli_2.png 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u5c0f\u8fa3\u6912 8\u6839<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t<a class=\"plain\" href=\"https:\/\/kampungcameron.com\/zh-hans\/product\/coriander\/\" >\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A20-Coriander_1-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A20-Coriander_1-300x300.png 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A20-Coriander_1-150x150.png 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A20-Coriander_1-768x768.png 768w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A20-Coriander_1-600x600.png 600w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A20-Coriander_1-100x100.png 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/A20-Coriander_1.png 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u9999\u83dc 6\u6839<\/p>\n\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t\t<div class=\"icon-box featured-box ingredients icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-300x300.jpg 300w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-150x150.jpg 150w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder-100x100.jpg 100w, https:\/\/kampungcameron.com\/wp-content\/uploads\/2023\/07\/placeholder.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p>\u67e0\u6aac 1\u7c92<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-1413103949\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1413103949 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h5>\u8c03\u5473\u6599:<\/h5>\n<li>\u751f\u62bd3\u52fa<\/li>\n<li>\u9c7c\u97322.5\u52fa<\/li>\n<li>\u767d\u7cd6\uff08\u5c1d\u5473\uff0c\u54b8\u6de1\u6309\u559c\u597d\u81ea\u884c\u8c03\u6574\uff0c\u6bd4\u4f8b\u53ea\u662f\u4e2a\u5927\u6982\u3002\uff09\n<\/li>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veggie-recipe-zh-hans"],"_links":{"self":[{"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/posts\/774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/comments?post=774"}],"version-history":[{"count":2,"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/posts\/774\/revisions"}],"predecessor-version":[{"id":903,"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/posts\/774\/revisions\/903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/media\/750"}],"wp:attachment":[{"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/categories?post=774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kampungcameron.com\/zh-hans\/wp-json\/wp\/v2\/tags?post=774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}